{"id":80,"date":"2021-10-18T15:53:23","date_gmt":"2021-10-18T18:53:23","guid":{"rendered":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647.jpg"},"modified":"2021-10-18T15:53:23","modified_gmt":"2021-10-18T18:53:23","slug":"adobestock_177732647","status":"inherit","type":"attachment","link":"https:\/\/assegurou.com.br\/blog\/seguro-auto-por-que-contratar\/adobestock_177732647\/","title":{"rendered":"AdobeStock_177732647"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-80","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>AdobeStock_177732647 - Blogou \u2013 assegurou<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\" \/>\r\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"AdobeStock_177732647 - Blogou \u2013 assegurou\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\" \/>\r\n<meta property=\"og:site_name\" content=\"Blogou \u2013 assegurou\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\",\"url\":\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\",\"name\":\"AdobeStock_177732647 - Blogou \u2013 assegurou\",\"isPartOf\":{\"@id\":\"https:\/\/assegurou.com.br\/blog\/#website\"},\"datePublished\":\"2021-10-18T18:53:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/assegurou.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seguro Autom\u00f3vel\",\"item\":\"https:\/\/assegurou.com.br\/blog\/category\/seguro-automovel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seguro auto: por que contratar?\",\"item\":\"https:\/\/assegurou.com.br\/blog\/seguro-auto-por-que-contratar\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"AdobeStock_177732647\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/assegurou.com.br\/blog\/#website\",\"url\":\"https:\/\/assegurou.com.br\/blog\/\",\"name\":\"Blogou \u2013 assegurou\",\"description\":\"Blogou \u2013 assegurou\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/assegurou.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AdobeStock_177732647 - Blogou \u2013 assegurou","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","og_locale":"pt_BR","og_type":"article","og_title":"AdobeStock_177732647 - Blogou \u2013 assegurou","og_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","og_site_name":"Blogou \u2013 assegurou","og_image":[{"width":2560,"height":1700,"url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","name":"AdobeStock_177732647 - Blogou \u2013 assegurou","isPartOf":{"@id":"https:\/\/assegurou.com.br\/blog\/#website"},"datePublished":"2021-10-18T18:53:23+00:00","breadcrumb":{"@id":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/assegurou.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Seguro Autom\u00f3vel","item":"https:\/\/assegurou.com.br\/blog\/category\/seguro-automovel\/"},{"@type":"ListItem","position":3,"name":"Seguro auto: por que contratar?","item":"https:\/\/assegurou.com.br\/blog\/seguro-auto-por-que-contratar\/"},{"@type":"ListItem","position":4,"name":"AdobeStock_177732647"}]},{"@type":"WebSite","@id":"https:\/\/assegurou.com.br\/blog\/#website","url":"https:\/\/assegurou.com.br\/blog\/","name":"Blogou \u2013 assegurou","description":"Blogou \u2013 assegurou","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/assegurou.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-300x199.jpg 300w, https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-1024x680.jpg 1024w, https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-768x510.jpg 768w, https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-1536x1020.jpg 1536w, https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-2048x1360.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1700,"file":"2021\/10\/AdobeStock_177732647-scaled.jpg","sizes":{"medium":{"file":"AdobeStock_177732647-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-300x199.jpg"},"large":{"file":"AdobeStock_177732647-1024x680.jpg","width":1024,"height":680,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-1024x680.jpg"},"thumbnail":{"file":"AdobeStock_177732647-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-150x150.jpg"},"medium_large":{"file":"AdobeStock_177732647-768x510.jpg","width":768,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-768x510.jpg"},"1536x1536":{"file":"AdobeStock_177732647-1536x1020.jpg","width":1536,"height":1020,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-1536x1020.jpg"},"2048x2048":{"file":"AdobeStock_177732647-2048x1360.jpg","width":2048,"height":1360,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-2048x1360.jpg"},"alm-thumbnail":{"file":"AdobeStock_177732647-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-150x150.jpg"},"full":{"file":"AdobeStock_177732647-scaled.jpg","width":2560,"height":1700,"mime_type":"image\/jpeg","source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"\u00a9 Rido","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"AdobeStock_177732647.jpg"},"post":79,"source_url":"https:\/\/assegurou.com.br\/blog\/wp-content\/uploads\/2021\/10\/AdobeStock_177732647-scaled.jpg","_links":{"self":[{"href":"https:\/\/assegurou.com.br\/blog\/wp-json\/wp\/v2\/media\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assegurou.com.br\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/assegurou.com.br\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/assegurou.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/assegurou.com.br\/blog\/wp-json\/wp\/v2\/comments?post=80"}]}}